{"id":3823,"date":"2019-04-02T20:18:56","date_gmt":"2019-04-02T19:18:56","guid":{"rendered":"http:\/\/zoyou.fr\/dessin\/?p=3823"},"modified":"2019-04-02T20:18:56","modified_gmt":"2019-04-02T19:18:56","slug":"fleabag","status":"publish","type":"post","link":"http:\/\/zoyou.fr\/dessin\/fleabag\/","title":{"rendered":"Fleabag"},"content":{"rendered":"<p>Fleabag est une s\u00e9rie que j&rsquo;ai commenc\u00e9 \u00e0 regarder tr\u00e8s r\u00e9cemment, en suivant les conseils de nombreux amis sur Tumblr. Bon, vous l&rsquo;avez probablement devin\u00e9 vu l&rsquo;image, Andrew Scott (aka mon acteur pr\u00e9f\u00e9r\u00e9) joue dedans. Mais outre sa pr\u00e9sence, la s\u00e9rie est tr\u00e8s bonne.<\/p>\n<p>Elle raconte la vie mouvement\u00e9e d&rsquo;une jeune londonienne surnomm\u00e9e Fleabag, entre son caf\u00e9 qui tombe en faillite, sa s\u0153ur avec qui elle entretient une relation compliqu\u00e9e, son p\u00e8re qui s&rsquo;appr\u00eate \u00e0 se remarier avec une m\u00e9g\u00e8re compl\u00e8te, son petit ami avec qui elle se s\u00e9pare r\u00e9guli\u00e8rement, et sa flop\u00e9e d&rsquo;amants. Fleabag a l&rsquo;habitude de commenter sa propre vie en regardant la cam\u00e9ra, elle a un humour ac\u00e9r\u00e9 et un tr\u00e8s fort caract\u00e8re, et tous les autres personnages autour d&rsquo;elle sont complexes, int\u00e9ressants et dr\u00f4les.<\/p>\n<p>&#8230;Oui, j&rsquo;essaie totalement de vous faire regarder cette s\u00e9rie.<\/p>\n<p>Bref, Andrew apparait dans la deuxi\u00e8me saison, et il joue un pr\u00eatre&#8230; dont Fleabag est tomb\u00e9e amoureuse. Pas de bol. Je ne vais pas vous spoiler, mais j&rsquo;ai d\u00e9vor\u00e9 toute la s\u00e9rie en un weekend (moins les deux \u00e9pisodes qui n&rsquo;\u00e9taient pas encore sortis) ce qui m&rsquo;a fil\u00e9 une hype monstre, qui a encore grandit en regardant le nouvel \u00e9pisode qui est sorti hier, et je suis actuellement en train de me ronger les sangs en attendant le final qui sort la semaine prochaine. Donc pour me faire patienter, j&rsquo;ai dessin\u00e9 Andrew Scott, aka le pr\u00eatre sexy.<\/p>\n<p><a href=\"http:\/\/zoyou.fr\/dessin\/wp-content\/uploads\/2019\/04\/fleabag-the-priest.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-3824\" src=\"http:\/\/zoyou.fr\/dessin\/wp-content\/uploads\/2019\/04\/fleabag-the-priest-1024x931.jpg\" alt=\"\" width=\"594\" height=\"540\" srcset=\"http:\/\/zoyou.fr\/dessin\/wp-content\/uploads\/2019\/04\/fleabag-the-priest-1024x931.jpg 1024w, http:\/\/zoyou.fr\/dessin\/wp-content\/uploads\/2019\/04\/fleabag-the-priest-300x273.jpg 300w, http:\/\/zoyou.fr\/dessin\/wp-content\/uploads\/2019\/04\/fleabag-the-priest-768x698.jpg 768w, http:\/\/zoyou.fr\/dessin\/wp-content\/uploads\/2019\/04\/fleabag-the-priest.jpg 1592w\" sizes=\"auto, (max-width: 594px) 100vw, 594px\" \/><\/a><\/p>\n<p>C&rsquo;est pas parfait niveau ressemblance, mais je suis plut\u00f4t contente des ombres et du style vitrail. Je n&rsquo;ai pas dessin\u00e9 le fond (pour changer&#8230;), c&rsquo;est une image prise sur Google. Je vais essayer de dessiner Fleabag bient\u00f4t, parce qu&rsquo;elle est vachement jolie, et cool, et que je l&rsquo;aime beaucoup, et BREF. C&rsquo;est pas s\u00fbr que j&rsquo;ai le temps remarque, ce mois ci je participe au Camp NaNoWriMo donc j&rsquo;ai d&rsquo;autres priorit\u00e9s.<\/p>\n<p>Sur ce, je retourne fangirler dans mon coin. Salut!<\/p>\n","protected":false},"excerpt":{"rendered":"Fleabag est une s\u00e9rie que j&rsquo;ai commenc\u00e9 \u00e0 regarder tr\u00e8s r\u00e9cemment, en suivant les conseils de nombreux amis sur Tumblr. Bon, vous l&rsquo;avez probablement devin\u00e9&hellip;","protected":false},"author":2,"featured_media":3824,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,17,14],"tags":[],"class_list":["post-3823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-accueil","category-autres-fandoms","category-fanarts"],"_links":{"self":[{"href":"http:\/\/zoyou.fr\/dessin\/wp-json\/wp\/v2\/posts\/3823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/zoyou.fr\/dessin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/zoyou.fr\/dessin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/zoyou.fr\/dessin\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/zoyou.fr\/dessin\/wp-json\/wp\/v2\/comments?post=3823"}],"version-history":[{"count":1,"href":"http:\/\/zoyou.fr\/dessin\/wp-json\/wp\/v2\/posts\/3823\/revisions"}],"predecessor-version":[{"id":3825,"href":"http:\/\/zoyou.fr\/dessin\/wp-json\/wp\/v2\/posts\/3823\/revisions\/3825"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/zoyou.fr\/dessin\/wp-json\/wp\/v2\/media\/3824"}],"wp:attachment":[{"href":"http:\/\/zoyou.fr\/dessin\/wp-json\/wp\/v2\/media?parent=3823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/zoyou.fr\/dessin\/wp-json\/wp\/v2\/categories?post=3823"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/zoyou.fr\/dessin\/wp-json\/wp\/v2\/tags?post=3823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}